{"id":10160,"date":"2021-11-08T13:00:00","date_gmt":"2021-11-08T12:00:00","guid":{"rendered":"https:\/\/phpstack-458049-1434344.cloudwaysapps.com\/?p=10160"},"modified":"2021-11-09T13:00:00","modified_gmt":"2021-11-09T12:00:00","slug":"streacom-tx13-waermeleitpaste","status":"publish","type":"post","link":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste","title":{"rendered":"Streacom TX13: High-End-W\u00e4rmeleitpaste mit Liebe zur Umwelt"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die TX13 von Streacom ist eine High-End-W\u00e4rmeleitpaste in jeder Hinsicht. Sie ist nicht elektrisch leitend und liefert mit einer W\u00e4rmeleitf\u00e4higkeit von imposanten 13,4 W\/(m\u00b7K) ordentlich ab. Damit ist sie sowohl f\u00fcr hitzige CPUs als auch Grafikkarten geeignet.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_01.jpg\" alt=\"\" class=\"wp-image-10221\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_01.jpg 800w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_01-300x300.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_01-150x150.jpg 150w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_01-768x768.jpg 768w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_01-462x462.jpg 462w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Die Paste kommt in f\u00fcnf perfekt vorportionierten Dosen. Diese beinhalten jeweils eine erbsengro\u00dfe Menge W\u00e4rmeleitpaste und eignen sich f\u00fcr genau eine Anwendung. In den einzelnen T\u00fctchen ist die Paste vor dem Austrocknen gesch\u00fctzt und du beh\u00e4ltst stets den \u00dcberblick \u00fcber die noch verf\u00fcgbaren Anwendungen. Kein R\u00e4tselraten mehr.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_02.jpg\" alt=\"\" class=\"wp-image-10220\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_02.jpg 800w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_02-300x300.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_02-150x150.jpg 150w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_02-768x768.jpg 768w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/zuwa_235_02-462x462.jpg 462w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Die TX13 setzt allerdings nicht nur auf eine hohe Leistung und einfache Anwendbarkeit. Als wenn das nicht schon genug w\u00e4re, legt Streacom auch gro\u00dfen Wert auf Nachhaltigkeit. Der Umwelt zuliebe ist die Verpackung der TX13 aus recyceltem Material gefertigt. Zus\u00e4tzlich wird pro verkaufter Einheit in Partnerschaft mit dem Eden Reforestation Project ein Baum gepflanzt. Gr\u00fcn, gr\u00fcner, Streacom.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.caseking.de\/Streacom-TX13-Waermeleitpaste-1-25-g-ZUWA-235.html\" target=\"_blank\" rel=\"noreferrer noopener\">Die TX13 W\u00e4rmeleitpaste im Caseking-Shop<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die TX13 von Streacom ist eine High-End-W&auml;rmeleitpaste in jeder Hinsicht. Sie ist nicht elektrisch leitend und liefert mit einer W&auml;rmeleitf&auml;higkeit von imposanten 13,4 W\/(m&middot;K) ordentlich ab. Damit ist sie sowohl f&uuml;r hitzige CPUs als auch Grafikkarten geeignet. Die Paste kommt in f&uuml;nf perfekt vorportionierten Dosen. Diese beinhalten jeweils eine erbsengro&szlig;e Menge W&auml;rmeleitpaste und eignen sich [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":10303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2230],"tags":[2484,709,2482,2483,1180],"class_list":["post-10160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caseking","tag-nachhaltigkeit","tag-streacom","tag-tx13","tag-umwelt","tag-warmeleitpaste"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Streacom TX13 W\u00e4rmeleitpaste: Leistung verbunden mit Nachhaltigkeit<\/title>\n<meta name=\"description\" content=\"Die TX13 spielt in Sachen Leistung in der obersten Liga mit. Aber auch Nachhaltigkeit ist Streacom wichtig, Stichwort: Baumpatenschaft.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Streacom TX13 W\u00e4rmeleitpaste: Leistung verbunden mit Nachhaltigkeit\" \/>\n<meta property=\"og:description\" content=\"Die TX13 spielt in Sachen Leistung in der obersten Liga mit. Aber auch Nachhaltigkeit ist Streacom wichtig, Stichwort: Baumpatenschaft.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste\" \/>\n<meta property=\"og:site_name\" content=\"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caseking\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-08T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-09T12:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/Blog-DE-Streacom-TX13.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marcel Bruns\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcel Bruns\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Streacom TX13 W\u00e4rmeleitpaste: Leistung verbunden mit Nachhaltigkeit","description":"Die TX13 spielt in Sachen Leistung in der obersten Liga mit. Aber auch Nachhaltigkeit ist Streacom wichtig, Stichwort: Baumpatenschaft.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste","og_locale":"de_DE","og_type":"article","og_title":"Streacom TX13 W\u00e4rmeleitpaste: Leistung verbunden mit Nachhaltigkeit","og_description":"Die TX13 spielt in Sachen Leistung in der obersten Liga mit. Aber auch Nachhaltigkeit ist Streacom wichtig, Stichwort: Baumpatenschaft.","og_url":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste","og_site_name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","article_publisher":"https:\/\/www.facebook.com\/caseking\/","article_published_time":"2021-11-08T12:00:00+00:00","article_modified_time":"2021-11-09T12:00:00+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/Blog-DE-Streacom-TX13.png","type":"image\/png"}],"author":"Marcel Bruns","twitter_misc":{"Verfasst von":"Marcel Bruns","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste#article","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste"},"author":{"name":"Marcel Bruns","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/499fc9c20cfe8b1a1edb06fa9b7b9c3b"},"headline":"Streacom TX13: High-End-W\u00e4rmeleitpaste mit Liebe zur Umwelt","datePublished":"2021-11-08T12:00:00+00:00","dateModified":"2021-11-09T12:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste"},"wordCount":174,"commentCount":0,"publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/Blog-DE-Streacom-TX13.png","keywords":["Nachhaltigkeit","Streacom","TX13","Umwelt","W\u00e4rmeleitpaste"],"articleSection":["Caseking"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste","url":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste","name":"Streacom TX13 W\u00e4rmeleitpaste: Leistung verbunden mit Nachhaltigkeit","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste#primaryimage"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/Blog-DE-Streacom-TX13.png","datePublished":"2021-11-08T12:00:00+00:00","dateModified":"2021-11-09T12:00:00+00:00","description":"Die TX13 spielt in Sachen Leistung in der obersten Liga mit. Aber auch Nachhaltigkeit ist Streacom wichtig, Stichwort: Baumpatenschaft.","breadcrumb":{"@id":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste#primaryimage","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/Blog-DE-Streacom-TX13.png","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/11\/Blog-DE-Streacom-TX13.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.caseking.de\/blog\/streacom-tx13-waermeleitpaste#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caseking.de\/blog"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.caseking.de\/blog\/category\/news"},{"@type":"ListItem","position":3,"name":"Caseking","item":"https:\/\/www.caseking.de\/blog\/category\/news\/caseking"},{"@type":"ListItem","position":4,"name":"Streacom TX13: High-End-W\u00e4rmeleitpaste mit Liebe zur Umwelt"}]},{"@type":"WebSite","@id":"https:\/\/www.caseking.de\/blog\/#website","url":"https:\/\/www.caseking.de\/blog\/","name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","description":"Die neuesten Hardware und Games News, Ger\u00fcchte, Trends und vieles mehr","publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caseking.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.caseking.de\/blog\/#organization","name":"Caseking GmbH","url":"https:\/\/www.caseking.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","width":367,"height":200,"caption":"Caseking GmbH"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/caseking\/","https:\/\/x.com\/caseking","https:\/\/www.instagram.com\/caseking.de","https:\/\/www.linkedin.com\/company\/caseking-gmbh\/","https:\/\/www.youtube.com\/channel\/UC8qA3SSeY04t_lWumt_SgEg"]},{"@type":"Person","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/499fc9c20cfe8b1a1edb06fa9b7b9c3b","name":"Marcel Bruns","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","caption":"Marcel Bruns"},"description":"Marcel stammt aus Bonn und ist im Berliner Umland aufgewachsen. Schon in der Schulzeit entwickelte er eine Leidenschaft f\u00fcr Technik und Gaming \u2013 seinen ersten PC zerlegte er direkt nach dem Auspacken, einfach um zu verstehen, wie er funktioniert. Bis heute baut er regelm\u00e4\u00dfig Gaming-PCs f\u00fcr sich und Freunde zusammen. Wenn er gerade nicht an seinem PC herumschraubt, taucht er gerne in die Welt der Anime ein und tr\u00e4umt davon, einmal Japan zu bereisen. In seiner Freizeit trifft man ihn entweder beim Zocken des neuesten AAA-Titels oder dabei, seine Teammates in League of Legends (mehr oder weniger absichtlich) zu inten.","url":"https:\/\/www.caseking.de\/blog\/author\/marcel-bruns"}]}},"_links":{"self":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/10160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/comments?post=10160"}],"version-history":[{"count":7,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/10160\/revisions"}],"predecessor-version":[{"id":10288,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/10160\/revisions\/10288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media\/10303"}],"wp:attachment":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media?parent=10160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/categories?post=10160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/tags?post=10160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}