{"id":11918,"date":"2022-01-15T10:00:00","date_gmt":"2022-01-15T09:00:00","guid":{"rendered":"https:\/\/phpstack-458049-1434344.cloudwaysapps.com\/?p=11918"},"modified":"2023-06-09T14:06:44","modified_gmt":"2023-06-09T12:06:44","slug":"begeisterung-steckt-an-casekings-19-geburtstag","status":"publish","type":"post","link":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag","title":{"rendered":"Begeisterung steckt an: Casekings 19. Geburtstag"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-top-banner-1024x208.png\" alt=\"\" class=\"wp-image-12009\" width=\"840\" height=\"170\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-top-banner-1024x208.png 1024w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-top-banner-300x61.png 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-top-banner-768x156.png 768w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-top-banner-1536x313.png 1536w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-top-banner-462x94.png 462w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-top-banner.png 1980w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Caseking kann nicht \u00e4lter werden, wenn die Technik jung bleibt. Mit 19 Jahren oder auch <em>Generationen<\/em> ist das Wissen rund um Hardware und Gaming gewachsen &#8211; <em>besser geworden<\/em>. Wir z\u00e4hlen mehr Jahre als Intel Generationen, was soll man mit all der Weisheit machen, wenn nicht <em>weitergeben<\/em>?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wir beschenken dich&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ja, dich! An unserem Geburtstag, dem 15. Januar, kannst du die Teilnahme an einem von sechs Workshops auf der Birthday-Page gewinnen. Wir stellen dir Experten und Influencer zur Verf\u00fcgung. Du kannst sie mit Fragen l\u00f6chern oder leise lauschen, was deine Lieblinge zu sagen haben.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.caseking.de\/lp\/happy-birthday-caseking-wird-19-jahre-alt.html\">Hier zelebrieren wir den Geburtstag!<\/a><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Welche Workshops gibt es?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Von Water-Cooling bis zu deiner eigenen Streaming-Karriere ist alles dabei. Es gibt einen wilden Mix zwischen Hardware-Gurus, eSports-Experten und Influencern. Kein Wunsch bleibt offen!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Overclocking POWERED BY Intel<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Fangirls und -Boys aufgepasst:<strong> Roman \u201cder8auer\u201d Hartung<\/strong> gibt euch die Ehre und bringt alles <em>pers\u00f6nlich<\/em> rund ums Thema Overclocking bei. Betonung: Vor Ort! Ein echtes Erlebnis zur Corona-Zeit &#8211; ganz f\u00fcr dich allein. Wie du jeden Tropfen Leistung aus deiner CPU gewinnst oder das hei\u00dfe St\u00fcck k\u00fchlen kannst, bringt dir kein anderer besser bei als <strong>der8auer<\/strong><em>.<\/em>&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Water-Cooling POWERED BY EK Water Blocks<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vor Graus zieht es bei einigen die Nackenhaare auf. Wasserk\u00fchlungen sehen fantastisch aus und sind vielleicht der letzte Schritt zum High-End Gaming-PC. Aber wie bleibt das dicht? <strong>Boris Bonnes<\/strong> zeigt dir, worauf es ankommt, damit dein System nicht baden geht. Ob du lernst Hardtubes zu biegen, Softtubes einzusetzen und mit welchen Komponenten Wasser zirkuliert, das alles und mehr bringt dir <strong>Boris Bonnes<\/strong> bei.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Case-Modding POWERED BY PHANTEKS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es hei\u00dft, PCs sitzen am besten auf Schreibtischen. Bei den Kunstwerken, die einige schaffen, kein Wunder!<strong> <\/strong>Denn Casekings Modder werden dir helfen, PC-Geh\u00e4use \u00e4sthetisch aufzuwerten. Sie servieren dir ganz extravagant die richtigen Materialien f\u00fcr dein Make-Over. Bestimmte Hardware oder Einzelteile wie gesleevte Kabel steigern die Attraktivit\u00e4t von PC-Geh\u00e4usen. <strong>Caseking<\/strong> wei\u00df, wie deine Komponenten strahlen werden.\u00a0<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Streaming POWERED BY Streamplify<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mit Gaming Geld verdienen. In wem von uns steckt nicht das kleine Kind, das ganz laut rebelliert und davon tr\u00e4umt Streamer zu sein? <strong>Meloonie<\/strong> hat es wahr gemacht und m\u00f6chte dir bei deiner Karriere oder zum Start einer helfen. Falls du dich schon immer gefragt hast, wie du Zuschauer in den Bann ziehst, welche technischen Anforderungen Streams setzen und wie du dich selbst in Szene setzt, wird dir <strong>Meloonie<\/strong> erkl\u00e4ren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Gaming und eSports POWERED BY Endgame Gear<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">eSports wird immer gr\u00f6\u00dfer und die Zug\u00e4nge einfacher. In kleinen Rahmen werden auf vielen Plattformen Turniere ausgetragen; man muss kein Profi mehr sein. Aber wenn man seine ersten Erfahrungen gemacht hat, wie geht es weiter? Ein <strong>erfolgreicher CS:GO-Spieler von Sprout <\/strong>m\u00f6chte dir<strong> <\/strong>mit<strong> Timo \u201cSpiidi\u201d Richter<\/strong> helfen, aus einem Hobby Karriere zu machen. Wie sollte dein Setup aussehen? Welche Motivation solltest du mitbringen? Wie viel Zeit solltest du investieren, um deine Chancen zu maximieren? <strong>Sprout und Spiidi<\/strong> stehen dir f\u00fcr all deine Fragen zur Verf\u00fcgung.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Keyboard-Customization POWERED BY Glorious PC Gaming Race<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sei dein eigener Schmied und forme dein wichtigstes Werkzeug! Neben all der tollen Hardware vergisst man seine Tastatur ganz schnell. Dabei setzt sie deine Gaming-Ma\u00dfst\u00e4be genauso wie deine Grafikkarte &#8211; vielleicht nicht optisch, aber sie dirigiert. Mit <strong>Daniel von der Kreativecke <\/strong>findest du heraus, wie du deine Tastatur mit verschiedenen Switches oder Keycaps pimpen kannst.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Zur \u00dcbersicht:&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Offline-Events sind:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Overclocking POWERED BY Intel&nbsp;<\/li>\n\n\n\n<li>Case-Modding POWERED BY PHANTEKS<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Die Online-Events sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Water-Cooling POWERED BY EK Water Blocks<\/li>\n\n\n\n<li>Streaming POWERED BY Streamplify<\/li>\n\n\n\n<li>Gaming und eSports POWERED BY Endgame Gear<\/li>\n\n\n\n<li>Keyboard-Modding POWERED BY Glorious PC Gaming Race<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Welches Produkt hast du im letzten Jahr gefeiert?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Du ben\u00f6tigst Inspiration f\u00fcr dein neues Setup oder du m\u00f6chtest dein Altes einfach aufwerten? Entdecke die Lieblingsprodukte des letzten Jahres! In 2022 wollen wir Wissen weitergeben &#8211; sei dabei und beweise auch deine Leidenschaft. <em>Hier ist nichts Standard.<\/em> Begeisterung w\u00e4chst zu etwas heran, das so fabelhaft ist, dass es jeden bewegt, sein Ding zu machen.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.caseking.de\/geburtstag?sPerPage=96\">Guck rein in die Produkte des Jahres<\/a><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Wir reichen dir unser Herz<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mit unseren Workshops teilen wir unsere Passion aus den letzten 19 Jahren. Wir m\u00f6chten dir etwas zur\u00fcckgeben. Darum verpasse den Geburtstag am 15. Januar nicht. Sei dabei und lass dich von unseren Geschenken berieseln.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"288\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-footer_2-1024x288.png\" alt=\"\" class=\"wp-image-12010\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-footer_2-1024x288.png 1024w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-footer_2-300x84.png 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-footer_2-768x216.png 768w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-footer_2-1536x431.png 1536w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-footer_2-462x130.png 462w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-footer_2.png 1980w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Caseking kann nicht \u00e4lter werden, wenn die Technik jung bleibt. Mit 19 Jahren oder auch Generationen ist das Wissen rund um Hardware und Gaming gewachsen &#8211; besser geworden. Wir z\u00e4hlen mehr Jahre als Intel Generationen, was soll man mit all der Weisheit machen, wenn nicht weitergeben?<\/p>\n","protected":false},"author":34,"featured_media":11919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2249],"tags":[270,751,501,198],"class_list":["post-11918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-featured-big","tag-caseking","tag-caseking-geburtstag","tag-gewinnspiel","tag-workshops"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Begeisterung steckt an: Casekings 19. Geburtstag<\/title>\n<meta name=\"description\" content=\"Caseking kann nicht \u00e4lter werden, wenn die Technik jung bleibt. Zu unserem Geburtstag geben wir dir 19 Jahre gesammeltes Wissen weiter.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Begeisterung steckt an: Casekings 19. Geburtstag\" \/>\n<meta property=\"og:description\" content=\"Caseking kann nicht \u00e4lter werden, wenn die Technik jung bleibt. Zu unserem Geburtstag geben wir dir 19 Jahre gesammeltes Wissen weiter.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag\" \/>\n<meta property=\"og:site_name\" content=\"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caseking\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-15T09:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-09T12:06:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-blog-02.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marcel Bruns\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcel Bruns\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Begeisterung steckt an: Casekings 19. Geburtstag","description":"Caseking kann nicht \u00e4lter werden, wenn die Technik jung bleibt. Zu unserem Geburtstag geben wir dir 19 Jahre gesammeltes Wissen weiter.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag","og_locale":"de_DE","og_type":"article","og_title":"Begeisterung steckt an: Casekings 19. Geburtstag","og_description":"Caseking kann nicht \u00e4lter werden, wenn die Technik jung bleibt. Zu unserem Geburtstag geben wir dir 19 Jahre gesammeltes Wissen weiter.","og_url":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag","og_site_name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","article_publisher":"https:\/\/www.facebook.com\/caseking\/","article_published_time":"2022-01-15T09:00:00+00:00","article_modified_time":"2023-06-09T12:06:44+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-blog-02.png","type":"image\/png"}],"author":"Marcel Bruns","twitter_misc":{"Verfasst von":"Marcel Bruns","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag#article","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag"},"author":{"name":"Marcel Bruns","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/499fc9c20cfe8b1a1edb06fa9b7b9c3b"},"headline":"Begeisterung steckt an: Casekings 19. Geburtstag","datePublished":"2022-01-15T09:00:00+00:00","dateModified":"2023-06-09T12:06:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag"},"wordCount":731,"commentCount":0,"publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-blog-02.png","keywords":["Caseking","Caseking Geburtstag","Gewinnspiel","Workshops"],"articleSection":["Highlight"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag","url":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag","name":"Begeisterung steckt an: Casekings 19. Geburtstag","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag#primaryimage"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-blog-02.png","datePublished":"2022-01-15T09:00:00+00:00","dateModified":"2023-06-09T12:06:44+00:00","description":"Caseking kann nicht \u00e4lter werden, wenn die Technik jung bleibt. Zu unserem Geburtstag geben wir dir 19 Jahre gesammeltes Wissen weiter.","breadcrumb":{"@id":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag#primaryimage","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-blog-02.png","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Caseking-19th-Anniversary-blog-02.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.caseking.de\/blog\/begeisterung-steckt-an-casekings-19-geburtstag#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caseking.de\/blog"},{"@type":"ListItem","position":2,"name":"Highlight","item":"https:\/\/www.caseking.de\/blog\/category\/featured-big"},{"@type":"ListItem","position":3,"name":"Begeisterung steckt an: Casekings 19. Geburtstag"}]},{"@type":"WebSite","@id":"https:\/\/www.caseking.de\/blog\/#website","url":"https:\/\/www.caseking.de\/blog\/","name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","description":"Die neuesten Hardware und Games News, Ger\u00fcchte, Trends und vieles mehr","publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caseking.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.caseking.de\/blog\/#organization","name":"Caseking GmbH","url":"https:\/\/www.caseking.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","width":367,"height":200,"caption":"Caseking GmbH"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/caseking\/","https:\/\/x.com\/caseking","https:\/\/www.instagram.com\/caseking.de","https:\/\/www.linkedin.com\/company\/caseking-gmbh\/","https:\/\/www.youtube.com\/channel\/UC8qA3SSeY04t_lWumt_SgEg"]},{"@type":"Person","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/499fc9c20cfe8b1a1edb06fa9b7b9c3b","name":"Marcel Bruns","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","caption":"Marcel Bruns"},"description":"Marcel stammt aus Bonn und ist im Berliner Umland aufgewachsen. Schon in der Schulzeit entwickelte er eine Leidenschaft f\u00fcr Technik und Gaming \u2013 seinen ersten PC zerlegte er direkt nach dem Auspacken, einfach um zu verstehen, wie er funktioniert. Bis heute baut er regelm\u00e4\u00dfig Gaming-PCs f\u00fcr sich und Freunde zusammen. Wenn er gerade nicht an seinem PC herumschraubt, taucht er gerne in die Welt der Anime ein und tr\u00e4umt davon, einmal Japan zu bereisen. In seiner Freizeit trifft man ihn entweder beim Zocken des neuesten AAA-Titels oder dabei, seine Teammates in League of Legends (mehr oder weniger absichtlich) zu inten.","url":"https:\/\/www.caseking.de\/blog\/author\/marcel-bruns"}]}},"_links":{"self":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/11918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/comments?post=11918"}],"version-history":[{"count":10,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/11918\/revisions"}],"predecessor-version":[{"id":18932,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/11918\/revisions\/18932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media\/11919"}],"wp:attachment":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media?parent=11918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/categories?post=11918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/tags?post=11918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}