{"id":12213,"date":"2022-01-29T10:30:00","date_gmt":"2022-01-29T09:30:00","guid":{"rendered":"https:\/\/phpstack-458049-1434344.cloudwaysapps.com\/?p=12213"},"modified":"2026-03-24T17:43:50","modified_gmt":"2026-03-24T16:43:50","slug":"intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel","status":"publish","type":"post","link":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel","title":{"rendered":"Intel Arc Alchemist &#8211; ein neuer Stern am Grafikkarten-Himmel?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wer an Intel denkt, denkt an Prozessoren. Aber dabei soll es nicht bleiben: Intel f\u00e4hrt ab 2022 zweigleisig. Mit Intel Arc Alchemist plant Intel nun auch den Einstieg in den Grafikkarten-Markt und m\u00f6chte dir eine Alternative zu den bisherigen Marktf\u00fchrern NVIDIA und AMD bieten. Die Ger\u00fcchtek\u00fcche brodelt flei\u00dfig vor sich hin. Wir haben dir im folgenden zusammengefasst, was schon \u00fcber Intels Pixelbeschleuniger bekannt ist.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Intel Arc Gameplay Trailer | The Game Awards 2021 | Intel Graphics\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/0dC6dz9CxYc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"wann-sollen-die-karten-kommen\"><strong>Wann sollen die Karten kommen?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Angek\u00fcndigt ist die erste Generation der Intel Arc Grafikkarten f\u00fcr 2022 &#8211; ein genaues Datum ist leider noch nicht bekannt. Aber keine Sorge, wir informieren dich, sobald es Neuigkeiten gibt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"welche-leistung-konnen-wir-erwarten\"><strong>Welche Leistung k\u00f6nnen wir erwarten?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aktuell hat Intel offiziell noch keine Bezeichnungen der einzelnen Karten genannt. Somit wissen wir auch noch nicht genau, wie viele Grafikkarten Intel tats\u00e4chlich auf den Markt bringen wird. Allerdings gibt es Ger\u00fcchte, dass das High-End-Modell von Alchemist mit einer RTX 3070 Ti von NVIDIA mithalten kann. Die Mittelklasse-Grafikkarte soll ungef\u00e4hr einer RTX 3060 entsprechen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"an-wen-richten-sich-intels-grafikkarten\"><strong>An wen richten sich Intels Grafikkarten?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Intel Arc ist Intels neue Marke f\u00fcr Gaming-Grafikkarten. Alchemist ist die erste Produkt-Reihe. Dabei erinnert der Name an typische Klassenbezeichnungen aus Rollenspielen. Der Wink mit dem Zaunpfahl, damit jeder erkennt, dass Intel Arc in erster Linie f\u00fcr Gaming entwickelt wird.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"xess-vs-fidelityfx-vs-dlss\"><strong>XeSS vs. FidelityFX vs. DLSS<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Auch in Sachen Gaming-Technologien steht Intel seinen beiden Konkurrenten in nichts nach: Mit XeSS (Xe Super Sampling) wird eine KI-Skalierungs-Technik \u00e4hnlich wie FidelityFX von AMD oder DLSS von NVIDIA, vorgestellt.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Technik soll f\u00fcr ein scharfes Bild und glatte Kanten sorgen und dabei noch extra FPS bringen. Die Besonderheit ist, dass XeSS auch Grafikkarten von AMD und NVIDIA unterst\u00fctzt.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-28-174440-1024x538.jpg\" alt=\"\" class=\"wp-image-12218\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-28-174440-1024x538.jpg 1024w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-28-174440-300x158.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-28-174440-768x404.jpg 768w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-28-174440-462x243.jpg 462w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-28-174440.jpg 1151w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>XeSS erh\u00f6ht die Bildqualit\u00e4t sp\u00fcrbar. <\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"intels-roadmap-fur-arc-grafikkarten\"><strong>Intels Roadmap f\u00fcr ARC-Grafikkarten<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn du denkst, dass Intel bis jetzt nur an der Alchemist-Reihe gearbeitet hat, dann schnall dich besser an. Intel hat schon die drei Nachfolgegenerationen in Petto<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Codename Alchemist<\/li><li>Codename Battlemage<\/li><li>Codename Celestial<\/li><li>Codename Druid<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Auf der offiziellen Website verspricht uns Intel eine Roadmap f\u00fcr seine neuen Pixelbeschleuniger &#8211; die \u00fcbrigens auch in naher Zukunft kommen soll. Abgesehen von den authentischen Namen der Serien ist aber noch nichts bekannt. Hier gilt also: Geduldig sein.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ein-neuer-stern-am-grafikkarten-himmel\"><strong>Ein neuer Stern am Grafikkarten Himmel!<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Selbst, wenn es noch keine offiziellen Leistungsdaten gibt und Ger\u00fcchte wie immer mit Vorsicht zu behandeln sind, klingt Intel Arc verhei\u00dfungsvoll. Wir sind auf jeden Fall \u00fcberaus gespannt auf Intels kommende Grafikkarten.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn sich die Ger\u00fcchte bewahrheiten, dann k\u00f6nnte Alchemist f\u00fcr Intel ein Erfolg werden, da es f\u00fcr Kunden eine echte Alternative beim Kauf von Gaming-Grafikkarten geben w\u00fcrde. Team Blau neben Team Gr\u00fcn und Rot.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie bei jedem anderen Markt gilt auch bei Grafikkarten: Mehr Konkurrenz bringt bessere und attraktivere Produkte hervor. Somit wird Intels Einstieg ziemlich sicher Leben in den eingestaubten Markt bringen und vermutlich der breiten Masse der Gamer zugutekommen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nat\u00fcrlich haben wir bei Caseking keine Glaskugel in einer Schublade unterm Schreibtisch, aber eines k\u00f6nnen wir dir mit Sicherheit sagen: Intel Arc Alchemist wird f\u00fcr viele Ver\u00e4nderungen sorgen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bist du genauso gespannt wie wir? Spielst du schon mit dem Gedanken, dir eine Alchemist-Karte zu kaufen? Lass uns doch gerne einen Kommentar da!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit Intel Arc Alchemist plant Intel nun auch den Einstieg in den Grafikkarten-Markt und m\u00f6chte dir eine Alternative zu den bisherigen Marktf\u00fchrern NVIDIA und AMD bieten. Die Ger\u00fcchtek\u00fcche brodelt flei\u00dfig vor sich hin. <\/p>\n","protected":false},"author":22,"featured_media":12215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236,2226,2231,2227],"tags":[2654,84,270,104,135,68,2653,2589,91],"class_list":["post-12213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geruchte","category-news","category-tech","category-tech-hardware","tag-alchemist","tag-amd","tag-caseking","tag-geruchtekuche","tag-grafikkarte","tag-intel","tag-intel-arc","tag-news","tag-nvidia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intel Arc Alchemist - ein neuer Stern am Grafikkarten-Himmel? - Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides<\/title>\n<meta name=\"description\" content=\"Mit Intel Arc Alchemist plant Intel nun auch den Einstieg in den Grafikkarten-Markt und m\u00f6chte dir eine Alternative zu den bisherigen Marktf\u00fchrern NVIDIA und AMD bieten. Die Ger\u00fcchtek\u00fcche brodelt flei\u00dfig vor sich hin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intel Arc Alchemist - ein neuer Stern am Grafikkarten-Himmel? - Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides\" \/>\n<meta property=\"og:description\" content=\"Mit Intel Arc Alchemist plant Intel nun auch den Einstieg in den Grafikkarten-Markt und m\u00f6chte dir eine Alternative zu den bisherigen Marktf\u00fchrern NVIDIA und AMD bieten. Die Ger\u00fcchtek\u00fcche brodelt flei\u00dfig vor sich hin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel\" \/>\n<meta property=\"og:site_name\" content=\"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caseking\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-29T09:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T16:43:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/1201732632018903.kM2SmC9W1FoRKTgn0mtp_height640.png\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marcel Fleischer\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcel Fleischer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intel Arc Alchemist - ein neuer Stern am Grafikkarten-Himmel? - Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","description":"Mit Intel Arc Alchemist plant Intel nun auch den Einstieg in den Grafikkarten-Markt und m\u00f6chte dir eine Alternative zu den bisherigen Marktf\u00fchrern NVIDIA und AMD bieten. Die Ger\u00fcchtek\u00fcche brodelt flei\u00dfig vor sich hin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel","og_locale":"de_DE","og_type":"article","og_title":"Intel Arc Alchemist - ein neuer Stern am Grafikkarten-Himmel? - Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","og_description":"Mit Intel Arc Alchemist plant Intel nun auch den Einstieg in den Grafikkarten-Markt und m\u00f6chte dir eine Alternative zu den bisherigen Marktf\u00fchrern NVIDIA und AMD bieten. Die Ger\u00fcchtek\u00fcche brodelt flei\u00dfig vor sich hin.","og_url":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel","og_site_name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","article_publisher":"https:\/\/www.facebook.com\/caseking\/","article_published_time":"2022-01-29T09:30:00+00:00","article_modified_time":"2026-03-24T16:43:50+00:00","og_image":[{"width":480,"height":480,"url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/1201732632018903.kM2SmC9W1FoRKTgn0mtp_height640.png","type":"image\/png"}],"author":"Marcel Fleischer","twitter_misc":{"Verfasst von":"Marcel Fleischer","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel#article","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel"},"author":{"name":"Marcel Fleischer","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/9e94f778157d45a98ed685f597b32da0"},"headline":"Intel Arc Alchemist &#8211; ein neuer Stern am Grafikkarten-Himmel?","datePublished":"2022-01-29T09:30:00+00:00","dateModified":"2026-03-24T16:43:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel"},"wordCount":563,"commentCount":2,"publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/1201732632018903.kM2SmC9W1FoRKTgn0mtp_height640.png","keywords":["Alchemist","amd","Caseking","Ger\u00fcchtek\u00fcche","Grafikkarte","intel","Intel Arc","News","nvidia"],"articleSection":["Ger\u00fcchte","News","Tech","Tech + Hardware"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel","url":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel","name":"Intel Arc Alchemist - ein neuer Stern am Grafikkarten-Himmel? - Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel#primaryimage"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/1201732632018903.kM2SmC9W1FoRKTgn0mtp_height640.png","datePublished":"2022-01-29T09:30:00+00:00","dateModified":"2026-03-24T16:43:50+00:00","description":"Mit Intel Arc Alchemist plant Intel nun auch den Einstieg in den Grafikkarten-Markt und m\u00f6chte dir eine Alternative zu den bisherigen Marktf\u00fchrern NVIDIA und AMD bieten. Die Ger\u00fcchtek\u00fcche brodelt flei\u00dfig vor sich hin.","breadcrumb":{"@id":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel#primaryimage","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/1201732632018903.kM2SmC9W1FoRKTgn0mtp_height640.png","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/01\/1201732632018903.kM2SmC9W1FoRKTgn0mtp_height640.png","width":480,"height":480,"caption":"Intel Arc Alchemist"},{"@type":"BreadcrumbList","@id":"https:\/\/www.caseking.de\/blog\/intel-arc-alchemist-ein-neuer-stern-am-grafikkarten-himmel#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caseking.de\/blog"},{"@type":"ListItem","position":2,"name":"Tech","item":"https:\/\/www.caseking.de\/blog\/category\/tech"},{"@type":"ListItem","position":3,"name":"Ger\u00fcchte","item":"https:\/\/www.caseking.de\/blog\/category\/tech\/geruchte"},{"@type":"ListItem","position":4,"name":"Intel Arc Alchemist &#8211; ein neuer Stern am Grafikkarten-Himmel?"}]},{"@type":"WebSite","@id":"https:\/\/www.caseking.de\/blog\/#website","url":"https:\/\/www.caseking.de\/blog\/","name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","description":"Die neuesten Hardware und Games News, Ger\u00fcchte, Trends und vieles mehr","publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caseking.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.caseking.de\/blog\/#organization","name":"Caseking GmbH","url":"https:\/\/www.caseking.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","width":367,"height":200,"caption":"Caseking GmbH"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/caseking\/","https:\/\/x.com\/caseking","https:\/\/www.instagram.com\/caseking.de","https:\/\/www.linkedin.com\/company\/caseking-gmbh\/","https:\/\/www.youtube.com\/channel\/UC8qA3SSeY04t_lWumt_SgEg"]},{"@type":"Person","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/9e94f778157d45a98ed685f597b32da0","name":"Marcel Fleischer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f4de02015770980dd8dad6afa7e03668e2762d9d35982d9e5381871de6427ba5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4de02015770980dd8dad6afa7e03668e2762d9d35982d9e5381871de6427ba5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4de02015770980dd8dad6afa7e03668e2762d9d35982d9e5381871de6427ba5?s=96&d=mm&r=g","caption":"Marcel Fleischer"},"description":"Marcel stammt aus Dresden und hat sich schon sehr fr\u00fch f\u00fcr Hardware und Technologie begeistert. Seine berufliche Erfahrung im Bereich IT und PC-Hardware sowie seine Leidenschaft f\u00fcr Custom-Wasserk\u00fchlungen und Overclocking pr\u00e4gen seine Beitr\u00e4ge im Caseking Blog. Hier schreibt Marcel \u00fcber Hardware-Innovationen, Technologie und spannende Trends rund um PC-Builds und Gaming. In seiner Freizeit verfolgt er die neuesten Techniktrends unter anderem von 'den Steves' - Gamers Nexus und Hardware Unboxed - und entspannt sich bei Spielen wie Path of Exile 2, Call of Duty oder spannenden Singleplayer-Abenteuern.","url":"https:\/\/www.caseking.de\/blog\/author\/mfleischer"}]}},"_links":{"self":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/12213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/comments?post=12213"}],"version-history":[{"count":5,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/12213\/revisions"}],"predecessor-version":[{"id":12220,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/12213\/revisions\/12220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media\/12215"}],"wp:attachment":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media?parent=12213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/categories?post=12213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/tags?post=12213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}