{"id":14300,"date":"2022-05-11T07:55:53","date_gmt":"2022-05-11T05:55:53","guid":{"rendered":"https:\/\/casekingblogloadbalancer-1418458831.eu-central-1.elb.amazonaws.com\/?p=14300"},"modified":"2026-03-24T17:43:32","modified_gmt":"2026-03-24T16:43:32","slug":"playstation-6-xbox2","status":"publish","type":"post","link":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2","title":{"rendered":"Stehen die PlayStation 6 und n\u00e4chste Xbox schon in den Startl\u00f6chern?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der Launch der PlayStation 5 und Xbox Series liegt nun bereits anderthalb Jahre zur\u00fcck und sind scheinbar trotzdem in geringerer St\u00fcckzahl verf\u00fcgbar als St\u00fchle bei der Reise nach Jerusalem. Maues Angebot, \u00fcberh\u00f6hte Preise und Next-Gen, das sich die Bezeichnung noch verdienen m\u00f6chte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese drei Attribute beschreiben den Launch der PS5 und Xbox Series wohl leider am treffendsten. Eine Stellenanzeige bei LinkedIn legt inzwischen sogar nahe, dass bereits an den Next-Next-Gen-Konsolen gewerkelt wird.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>AMD, Sony und Microsoft schlafen nicht<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Laut einer <a href=\"https:\/\/www.linkedin.com\/jobs\/view\/system-on-chip-verification-engineer-160442-at-amd-3061207967\/\">Stellenausschreibung von AMD<\/a> arbeitet Team Red schon an einem neuen SoC f\u00fcr die vermeintliche PlayStation 6 und n\u00e4chste Xbox. Gesucht wird ein Chip-Architekt, der die Hardware-Komponenten f\u00fcr die n\u00e4chste Generation entwickelt.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Stellenanzeige liest sich wie folgt: \u201eDas Team, das hinter dem Chip f\u00fcr XBOX, PlayStation und dem neuesten Grafikchip der RDNA-Familie steht, stellt f\u00fcr seinen Standort in Markham, Kanada, Mitarbeiter f\u00fcr das Chip-Entwicklungsprojekt der n\u00e4chsten Generation ein!\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Kommt nun bereits Next-Next-Gen?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Definitiv nein. Es ist \u00fcblich, dass Unternehmen mit Blick auf die Zukunft bereits an Projekten arbeiten, die noch einige Jahre entfernt liegen. Stillstand bedeutet bekanntlich R\u00fcckschritt. <\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"528\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/xbox_series_x_vs._playstation_5__vergleich_der_technischen_daten_1-1024x528.jpg\" alt=\"Das Bild zeigt die PlayStation 5 und Xbox Series X\" class=\"wp-image-14302\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/xbox_series_x_vs._playstation_5__vergleich_der_technischen_daten_1-1024x528.jpg 1024w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/xbox_series_x_vs._playstation_5__vergleich_der_technischen_daten_1-300x155.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/xbox_series_x_vs._playstation_5__vergleich_der_technischen_daten_1-768x396.jpg 768w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/xbox_series_x_vs._playstation_5__vergleich_der_technischen_daten_1-1536x791.jpg 1536w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/xbox_series_x_vs._playstation_5__vergleich_der_technischen_daten_1-462x238.jpg 462w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/xbox_series_x_vs._playstation_5__vergleich_der_technischen_daten_1.jpg 1747w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ein typischer Konsolen-Lebenszyklus dauert etwa sieben Jahre an. Im Umkehrschluss haben die neuen Konsolen aus dem Hause Sony und Microsoft noch gute f\u00fcnf Jahre vor sich.&nbsp;Zudem haben Entwickler nicht einmal ansatzweise an der Leistungsgrenze der neuen Konsolen gekratzt. Dies illustriert uns die  <a href=\"https:\/\/www.caseking.de\/blog\/unreal-engine-5\/\">Unreal Engine 5<\/a> immer wieder aufs neue. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>PlayStation 5 Pro und Xbox Series X\u2026Pro?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aufgrund der dauernden Verschiebungen von Spielen und einer Chip-Knappheit, die vermutlich noch bis 2024 andauern wird, l\u00e4sst sich jedoch selbst das nicht vorhersagen. Vielleicht werkeln die PS5 und Xbox-Series-Konsolen deutlich l\u00e4nger als \u00fcblich.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Genauso k\u00f6nnte die Stellenausschreibung auf eine Pro-Variante der PS5 und Xbox Series hindeuten. Insbesondere Sony soll wohl emsig an einer Raytracing-Optimierung f\u00fcr die eigene Konsole arbeiten, wie ein Patent von PS5-Chefarchitekt Mark Cerny andeutet.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/twitter.com\/Onion00048\/status\/1497216277953265682?ref_src=twsrc%5Etfw%7Ctwcamp%5Etweetembed%7Ctwterm%5E1497216277953265682%7Ctwgr%5E%7Ctwcon%5Es1_c10&#038;ref_url=https%3A%2F%2Fwww.pcgameshardware.de%2FPlaystation-5-Konsolen-265878%2FNews%2FRaytracing-Patent-Sony-1390152%2F\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Der Launch der PlayStation 5 und Xbox Series liegt nun bereits anderthalb Jahre zur&uuml;ck und sind scheinbar trotzdem in geringerer St&uuml;ckzahl verf&uuml;gbar als St&uuml;hle bei der Reise nach Jerusalem. Maues Angebot, &uuml;berh&ouml;hte Preise und Next-Gen, das sich die Bezeichnung noch verdienen m&ouml;chte. Diese drei Attribute beschreiben den Launch der PS5 und Xbox Series wohl leider [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":14322,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2237,2236,2241],"tags":[2672,2681,2417,2418],"class_list":["post-14300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gaming","category-geruchte","category-konsolen","tag-konsolen","tag-next-gen","tag-playstation","tag-xbox"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stehen die PlayStation 6 und n\u00e4chste Xbox schon in den Startl\u00f6chern?<\/title>\n<meta name=\"description\" content=\"Laut einer Stellenausschreibung von AMD werkeln Sony und Microsoft bereits an der PlayStation 6 und n\u00e4chsten Xbox.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stehen die PlayStation 6 und n\u00e4chste Xbox schon in den Startl\u00f6chern?\" \/>\n<meta property=\"og:description\" content=\"Laut einer Stellenausschreibung von AMD werkeln Sony und Microsoft bereits an der PlayStation 6 und n\u00e4chsten Xbox.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2\" \/>\n<meta property=\"og:site_name\" content=\"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caseking\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-11T05:55:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T16:43:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/1202253325997123.5tGNxae4PfWXB0imRd5W_height640.png\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marcel Bruns\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcel Bruns\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stehen die PlayStation 6 und n\u00e4chste Xbox schon in den Startl\u00f6chern?","description":"Laut einer Stellenausschreibung von AMD werkeln Sony und Microsoft bereits an der PlayStation 6 und n\u00e4chsten Xbox.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2","og_locale":"de_DE","og_type":"article","og_title":"Stehen die PlayStation 6 und n\u00e4chste Xbox schon in den Startl\u00f6chern?","og_description":"Laut einer Stellenausschreibung von AMD werkeln Sony und Microsoft bereits an der PlayStation 6 und n\u00e4chsten Xbox.","og_url":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2","og_site_name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","article_publisher":"https:\/\/www.facebook.com\/caseking\/","article_published_time":"2022-05-11T05:55:53+00:00","article_modified_time":"2026-03-24T16:43:32+00:00","og_image":[{"width":480,"height":480,"url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/1202253325997123.5tGNxae4PfWXB0imRd5W_height640.png","type":"image\/png"}],"author":"Marcel Bruns","twitter_misc":{"Verfasst von":"Marcel Bruns","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2#article","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2"},"author":{"name":"Marcel Bruns","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/499fc9c20cfe8b1a1edb06fa9b7b9c3b"},"headline":"Stehen die PlayStation 6 und n\u00e4chste Xbox schon in den Startl\u00f6chern?","datePublished":"2022-05-11T05:55:53+00:00","dateModified":"2026-03-24T16:43:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2"},"wordCount":368,"commentCount":0,"publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/1202253325997123.5tGNxae4PfWXB0imRd5W_height640.png","keywords":["Konsolen","Next-Gen","PlayStation","Xbox"],"articleSection":["Gaming","Ger\u00fcchte","Konsolen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.caseking.de\/blog\/playstation-6-xbox2#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2","url":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2","name":"Stehen die PlayStation 6 und n\u00e4chste Xbox schon in den Startl\u00f6chern?","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2#primaryimage"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/1202253325997123.5tGNxae4PfWXB0imRd5W_height640.png","datePublished":"2022-05-11T05:55:53+00:00","dateModified":"2026-03-24T16:43:32+00:00","description":"Laut einer Stellenausschreibung von AMD werkeln Sony und Microsoft bereits an der PlayStation 6 und n\u00e4chsten Xbox.","breadcrumb":{"@id":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caseking.de\/blog\/playstation-6-xbox2"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2#primaryimage","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/1202253325997123.5tGNxae4PfWXB0imRd5W_height640.png","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2022\/05\/1202253325997123.5tGNxae4PfWXB0imRd5W_height640.png","width":480,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.caseking.de\/blog\/playstation-6-xbox2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caseking.de\/blog"},{"@type":"ListItem","position":2,"name":"Gaming","item":"https:\/\/www.caseking.de\/blog\/category\/gaming"},{"@type":"ListItem","position":3,"name":"Stehen die PlayStation 6 und n\u00e4chste Xbox schon in den Startl\u00f6chern?"}]},{"@type":"WebSite","@id":"https:\/\/www.caseking.de\/blog\/#website","url":"https:\/\/www.caseking.de\/blog\/","name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","description":"Die neuesten Hardware und Games News, Ger\u00fcchte, Trends und vieles mehr","publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caseking.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.caseking.de\/blog\/#organization","name":"Caseking GmbH","url":"https:\/\/www.caseking.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","width":367,"height":200,"caption":"Caseking GmbH"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/caseking\/","https:\/\/x.com\/caseking","https:\/\/www.instagram.com\/caseking.de","https:\/\/www.linkedin.com\/company\/caseking-gmbh\/","https:\/\/www.youtube.com\/channel\/UC8qA3SSeY04t_lWumt_SgEg"]},{"@type":"Person","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/499fc9c20cfe8b1a1edb06fa9b7b9c3b","name":"Marcel Bruns","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","caption":"Marcel Bruns"},"description":"Marcel stammt aus Bonn und ist im Berliner Umland aufgewachsen. Schon in der Schulzeit entwickelte er eine Leidenschaft f\u00fcr Technik und Gaming \u2013 seinen ersten PC zerlegte er direkt nach dem Auspacken, einfach um zu verstehen, wie er funktioniert. Bis heute baut er regelm\u00e4\u00dfig Gaming-PCs f\u00fcr sich und Freunde zusammen. Wenn er gerade nicht an seinem PC herumschraubt, taucht er gerne in die Welt der Anime ein und tr\u00e4umt davon, einmal Japan zu bereisen. In seiner Freizeit trifft man ihn entweder beim Zocken des neuesten AAA-Titels oder dabei, seine Teammates in League of Legends (mehr oder weniger absichtlich) zu inten.","url":"https:\/\/www.caseking.de\/blog\/author\/marcel-bruns"}]}},"_links":{"self":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/14300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/comments?post=14300"}],"version-history":[{"count":4,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/14300\/revisions"}],"predecessor-version":[{"id":14324,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/14300\/revisions\/14324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media\/14322"}],"wp:attachment":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media?parent=14300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/categories?post=14300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/tags?post=14300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}