{"id":4903,"date":"2020-10-21T08:00:00","date_gmt":"2020-10-21T06:00:00","guid":{"rendered":"https:\/\/www.caseking.de\/blog\/?p=4903"},"modified":"2020-10-21T08:41:20","modified_gmt":"2020-10-21T06:41:20","slug":"amd-renoir-for-business-kleine-kraftpakete-furs-home-office","status":"publish","type":"post","link":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office","title":{"rendered":"AMD Ryzen Pro: Renoir-Prozessoren mit iGPU f\u00fcrs Home-Office"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Man nehme eine Renoir-APU und stecke sie in ein Desktop-Geh\u00e4use. Die f\u00fcr Notebooks konzipierten AMD Ryzen Pro-Prozessoren mit integrierter Vega-Grafikeinheit kombinieren Effizienz mit Leistung. Daher stellen sie eine gute Wahl als Basis f\u00fcr Office-Systeme dar.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Die CPU-Performance entspricht den Desktop-Counterparts, w\u00e4hrend die integrierte Grafikeinheit das Spielen beliebter Online-Titel erm\u00f6glicht. Und das ohne gro\u00dfe Abstriche. Dabei bieten die Renoir-APUs zus\u00e4tzlich RAM-OC bis 3.200 MHz.<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Die Prozessoren mit Pro-Technologien verf\u00fcgen zudem \u00fcber Features wie AMD Memory Guard, das Echtzeitverschl\u00fcsselung des Systemspeichers erm\u00f6glicht. Zus\u00e4tzlich bietet Ryzen Pro Funktionen zur Fernverwaltung.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Unsere Experten vom King Mod-Team haben sich die drei Renoir-APUs direkt geschnappt und zu jeden APUs Business-Systeme zusammengestellt, die ein herausragendes Preis-Leistungs-Verh\u00e4ltnis bieten.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/AMD-Pro-1024x576.jpg\" alt=\"\" class=\"wp-image-4906\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/AMD-Pro-1024x576.jpg 1024w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/AMD-Pro-300x169.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/AMD-Pro-768x432.jpg 768w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/AMD-Pro-462x260.jpg 462w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/AMD-Pro.jpg 1260w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>AMD Ryzen Pro (Quelle: AMD)<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator is-style-wide\"\/>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">AMD Ryzen 3 PRO 4350G<\/h2>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Die kleinste der drei Ryzen Pro-APUs bietet eine mit dem Ryzen 3 3100 vergleichbare CPU-Rechenleistung. 4 Zen2-Rechenkerne mit 8 Threads takten im Turbo auf bis zu 4.0 GHz. Die Vega6-Grafikeinheit ist bei 1080p vergleichbar mit einer Einsteiger-Grafikkarte und erzielt zum Beispiel bei <em>Valorant<\/em> durchschnittlich 200 FPS (mittlere Details, Ergebnisse k\u00f6nnen abweichen, <a href=\"https:\/\/www.computerbase.de\/2020-10\/amd-ryzen-3-4350g-test\/#diagramm-valorant-1080p-mittel\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Computerbase<\/a>). <\/p>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In unserem <a href=\"https:\/\/www.caseking.de\/king-mod-systems-pro-mini-amd-ryzen-pro-4350g-for-business-sipc-315.html\">Pro Mini<\/a> hat das King Mod-Team den Ryzen Pro 4350G mit einem Mini-ITX-Mainboard Gigabyte B550I Aorus Pro AX gepaart. Zusammen mit 8 GB Arbeitsspeicher und einer 256 GB gro\u00dfen NVMe-SSD, wurde das kleine Kraftpaket in einem eleganten Chopin-Geh\u00e4use von InWin untergebracht. F\u00fcr die K\u00fchlung der APU kommt ein Noctua NH-L9a-AM4 CPU-K\u00fchler zum Einsatz!<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/sipc-315.jpg\" alt=\"\" class=\"wp-image-4907\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/sipc-315.jpg 800w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/sipc-315-300x300.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/sipc-315-150x150.jpg 150w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/sipc-315-768x768.jpg 768w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/sipc-315-462x462.jpg 462w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>Pro Mini: Renoir meets Chopin<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator is-style-wide\"\/>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">AMD Ryzen Pro 4650G<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mit 6 Kernen, 12 Threads und einem Turbotakt von 4.2 GHz bildet der AMD Ryzen 5 Pro 4650G die &#8222;Mittelklasse&#8220; der Renoir-APUs. Die Rechenleistung der Renoir-APU ist mit dem des AMD Ryzen 5 3600 vergleichbar. Die Vega7-iGPU ist etwas st\u00e4rker als beim Einsteigermodell.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der <a href=\"https:\/\/www.caseking.de\/king-mod-systems-pro-micro-amd-ryzen-pro-4650g-for-business-sipc-319.html\">King Mod Systems Pro Micro<\/a> kombiniert die Renoir-APU mit einem Micro-ATX-Mainboard und wird in einem kompakten Kolink-Geh\u00e4use ausgeliefert. Durch den Wechsel auf Micro-ATX kann nicht nur ein gr\u00f6\u00dferer CPU-L\u00fcfterverbaut werden. Die zus\u00e4tzlichen Erweiterungspl\u00e4tze erm\u00f6glichen das Upgraden mit zus\u00e4tzlichen Erweiterungskarten. Neben einer dedizierten Grafikkarte k\u00f6nnen hier zum Beispiel Netzwerk\/WLAN-Karten oder Capture-Karten zum Streamen verbaut werden.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-319.jpg\" alt=\"\" class=\"wp-image-4914\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-319.jpg 800w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-319-300x300.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-319-150x150.jpg 150w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-319-768x768.jpg 768w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-319-462x462.jpg 462w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>Pro Micro: Klein, aber Oho<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator is-style-wide\"\/>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">AMD Ryzen 7 PRO 4750G<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Performancerating f\u00fcr Anwendungen (Computerbase.de) liegt die AMD Ryzen 7 PRO 4750G Renoir-APU fast gleichauf mit einem Ryzen 7 3700X. Beide bieten 8 Kerne und 16 Threads, doch der Desktop-Prozessor kann auf Basis eines h\u00f6heren Stromverbrauchs den Boost-Takt von 4.4 GHz l\u00e4nger aufrecht erhalten. Und nat\u00fcrlich hat der 4750G noch eine Vega8-iGPU mit an Board.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das einzige, was dem <a href=\"https:\/\/www.caseking.de\/king-mod-systems-pro-maxi-amd-ryzen-pro-4750g-for-business-sipc-320.html\">Pro Maxi<\/a> zum High-End-Gaming-PC fehlt, ist die dedizierte <a href=\"https:\/\/www.caseking.de\/pc-komponenten\/grafikkarten\">Grafikkarte<\/a>. Um den Rechner entsprechend aufr\u00fcsten zu k\u00f6nnen, wurde vom King Mod-Team ein Tower-Geh\u00e4use ausgew\u00e4hlt. <\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-320.jpg\" alt=\"\" class=\"wp-image-4910\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-320.jpg 800w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-320-300x300.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-320-150x150.jpg 150w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-320-768x768.jpg 768w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/12\/sipc-320-462x462.jpg 462w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption>Pro Maxi: Dezent und Erweiterbar<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator is-style-wide\"\/>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Home-Office &amp; Gaming in Einem<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die hohe Leistung der Ryzen Pro 4000-Serie ist nicht nur f\u00fcr Business-Kunden ein enormer Vorteil. Arbeit von zuhause via Remote-Login mit gleichzeitigem Surfen im Internet kann hohe Anspr\u00fcche an die CPU stellen. Die Multi-Thread-Power der AMD Ryzen Pro 4000 APUs (APU = Accelerated Processing Unit) und mithilfe von Ryzen werden unsere Office-Systeme zu kleinen Kraftprotzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Einen Beitrag zur Work-Life-Balance bieten unsere Home-Office- und Business-Systeme gleich mit dazu. Dann dank der integrierten Grafikeinheit der Ryzen Pro-APUs kann man mit seinen Kollegen, seinen Freunden oder der Familie auch Online Gamen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caseking bietet aber nat\u00fcrlich auch Home-Office-Systeme mit einem Intel Core-Prozessor an. Zum Beispiel bei unseren <a href=\"https:\/\/www.caseking.de\/pc-systeme\/24h-express-systeme\">24-h-Expresssystemen<\/a> kann ein solches System gefunden werden.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator is-style-wide\"\/>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Noch mehr Leistung durch \u00dcbertakten!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das bereits herausragende Leistungspotential der AMD Pro-Serie kann durch manuelles \u00dcbertakten der Renoir-Prozessoren noch weiter erh\u00f6ht werden. Bei AMDs APUs k\u00f6nnen CPU und integrierte Grafikeinheit getrennt voneinander \u00dcbertaktet werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zum \u00dcbertakten (OC, Over Clocking) kann AMDs Ryzen Master-Tool verwendet werden. Einen \u00dcberblick \u00fcber die Software gibt es in unserem kleinen <a href=\"https:\/\/www.caseking.de\/blog\/amd-ryzen-ganz-einfach-uebertakten-mit-amd-ryzen-master\/\">Ratgeber<\/a> zu dem Thema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es ist aber auch m\u00f6glich, die Renoir-APUs durch &#8222;Undervolting&#8220; noch effizienter Arbeiten zu lassen &#8211; mit entsprechender Einbu\u00dfe bei der Leistung. Und auch das Feintunen des Arbeitsspeichers ist m\u00f6glich.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Ma\u00dfnahmen erh\u00f6hen nicht nur die Leistung der Ryzen Pro 4000 Serie, sonders k\u00f6nnen auch die leistungsabh\u00e4ngige Notwendigkeit zum Austausch der Ryzen Pro-CPUs hinausz\u00f6gern. Allerdings kann es Notwendig sein, einen gr\u00f6\u00dferen CPU-K\u00fchler zu verwenden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tests durchgef\u00fchrt im AMD Leistungslabor zeigen die vom <a href=\"https:\/\/www.amd.com\/de\/ryzen-pro\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Hersteller<\/a> ermittelte Performance der AMD-Prozessoren mit Pro Technologie. Externe Benchmarks zeigen zum Beispiel die Performance des 4650G von \u00fcber 3.400 <a href=\"https:\/\/nanoreview.net\/en\/cpu-list\/cinebench-r20-scores\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Punkten<\/a>  im Cinebench R20.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caseking stellt seine neuen Office- &#038; Home-Office-Systeme mit den AMD Ryzen Pro-APUs vor.<\/p>\n","protected":false},"author":34,"featured_media":4904,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2230,2226],"tags":[2284,2283,2286,2285],"class_list":["post-4903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-caseking","category-news","tag-amd-pro","tag-business-systeme","tag-home-office-pc","tag-renoir"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMD Ryzen Pro: Renoir-Prozessoren mit iGPU f\u00fcrs Home-Office - Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides<\/title>\n<meta name=\"description\" content=\"Caseking stellt seine neuen Office- &amp; Home-Office-Systeme mit den AMD Ryzen Pro-APUs vor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMD Ryzen Pro: Renoir-Prozessoren mit iGPU f\u00fcrs Home-Office - Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides\" \/>\n<meta property=\"og:description\" content=\"Caseking stellt seine neuen Office- &amp; Home-Office-Systeme mit den AMD Ryzen Pro-APUs vor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office\" \/>\n<meta property=\"og:site_name\" content=\"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caseking\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-21T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-21T06:41:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/Blog-DE-AMD-FOR-BUSINESS.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marcel Bruns\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcel Bruns\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMD Ryzen Pro: Renoir-Prozessoren mit iGPU f\u00fcrs Home-Office - Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","description":"Caseking stellt seine neuen Office- & Home-Office-Systeme mit den AMD Ryzen Pro-APUs vor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office","og_locale":"de_DE","og_type":"article","og_title":"AMD Ryzen Pro: Renoir-Prozessoren mit iGPU f\u00fcrs Home-Office - Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","og_description":"Caseking stellt seine neuen Office- & Home-Office-Systeme mit den AMD Ryzen Pro-APUs vor.","og_url":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office","og_site_name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","article_publisher":"https:\/\/www.facebook.com\/caseking\/","article_published_time":"2020-10-21T06:00:00+00:00","article_modified_time":"2020-10-21T06:41:20+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/Blog-DE-AMD-FOR-BUSINESS.png","type":"image\/png"}],"author":"Marcel Bruns","twitter_misc":{"Verfasst von":"Marcel Bruns","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office#article","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office"},"author":{"name":"Marcel Bruns","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/499fc9c20cfe8b1a1edb06fa9b7b9c3b"},"headline":"AMD Ryzen Pro: Renoir-Prozessoren mit iGPU f\u00fcrs Home-Office","datePublished":"2020-10-21T06:00:00+00:00","dateModified":"2020-10-21T06:41:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office"},"wordCount":742,"commentCount":0,"publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/Blog-DE-AMD-FOR-BUSINESS.png","keywords":["AMD Pro","Business Systeme","Home-Office-PC","Renoir"],"articleSection":["Caseking","News"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office","url":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office","name":"AMD Ryzen Pro: Renoir-Prozessoren mit iGPU f\u00fcrs Home-Office - Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office#primaryimage"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/Blog-DE-AMD-FOR-BUSINESS.png","datePublished":"2020-10-21T06:00:00+00:00","dateModified":"2020-10-21T06:41:20+00:00","description":"Caseking stellt seine neuen Office- & Home-Office-Systeme mit den AMD Ryzen Pro-APUs vor.","breadcrumb":{"@id":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office#primaryimage","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/Blog-DE-AMD-FOR-BUSINESS.png","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/10\/Blog-DE-AMD-FOR-BUSINESS.png","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.caseking.de\/blog\/amd-renoir-for-business-kleine-kraftpakete-furs-home-office#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caseking.de\/blog"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.caseking.de\/blog\/category\/news"},{"@type":"ListItem","position":3,"name":"AMD Ryzen Pro: Renoir-Prozessoren mit iGPU f\u00fcrs Home-Office"}]},{"@type":"WebSite","@id":"https:\/\/www.caseking.de\/blog\/#website","url":"https:\/\/www.caseking.de\/blog\/","name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","description":"Die neuesten Hardware und Games News, Ger\u00fcchte, Trends und vieles mehr","publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caseking.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.caseking.de\/blog\/#organization","name":"Caseking GmbH","url":"https:\/\/www.caseking.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","width":367,"height":200,"caption":"Caseking GmbH"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/caseking\/","https:\/\/x.com\/caseking","https:\/\/www.instagram.com\/caseking.de","https:\/\/www.linkedin.com\/company\/caseking-gmbh\/","https:\/\/www.youtube.com\/channel\/UC8qA3SSeY04t_lWumt_SgEg"]},{"@type":"Person","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/499fc9c20cfe8b1a1edb06fa9b7b9c3b","name":"Marcel Bruns","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97f54f496f36a2d7f73c2e95b889c7aaf3aa20866625c2f7d7b9852fa0e6573c?s=96&d=mm&r=g","caption":"Marcel Bruns"},"description":"Marcel stammt aus Bonn und ist im Berliner Umland aufgewachsen. Schon in der Schulzeit entwickelte er eine Leidenschaft f\u00fcr Technik und Gaming \u2013 seinen ersten PC zerlegte er direkt nach dem Auspacken, einfach um zu verstehen, wie er funktioniert. Bis heute baut er regelm\u00e4\u00dfig Gaming-PCs f\u00fcr sich und Freunde zusammen. Wenn er gerade nicht an seinem PC herumschraubt, taucht er gerne in die Welt der Anime ein und tr\u00e4umt davon, einmal Japan zu bereisen. In seiner Freizeit trifft man ihn entweder beim Zocken des neuesten AAA-Titels oder dabei, seine Teammates in League of Legends (mehr oder weniger absichtlich) zu inten.","url":"https:\/\/www.caseking.de\/blog\/author\/marcel-bruns"}]}},"_links":{"self":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/4903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/comments?post=4903"}],"version-history":[{"count":7,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/4903\/revisions"}],"predecessor-version":[{"id":4926,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/4903\/revisions\/4926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media\/4904"}],"wp:attachment":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media?parent=4903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/categories?post=4903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/tags?post=4903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}