{"id":5045,"date":"2020-11-06T07:00:00","date_gmt":"2020-11-06T06:00:00","guid":{"rendered":"https:\/\/www.caseking.de\/blog\/?p=5045"},"modified":"2025-04-01T10:34:18","modified_gmt":"2025-04-01T08:34:18","slug":"amd-ryzen-workstation-mainboards","status":"publish","type":"post","link":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards","title":{"rendered":"Content Creator Workstation mit AMD Ryzen und X570"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards\/#Was_ist_ein_Content_Creator\" >Was ist ein Content Creator?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards\/#Leistungsbedarf_von_Programmen\" >Leistungsbedarf von Programmen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards\/#Hoehere_Transferraten_und_mehr_Bandbreite_durch_PCI-Express_40\" >H\u00f6here Transferraten und mehr Bandbreite durch PCI-Express 4.0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards\/#MSI_Prestige_X570_Creation_fuer_besonders_viele_NVMe_SSDs\" >MSI Prestige X570 Creation f\u00fcr besonders viele NVMe SSDs<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards\/#ASRock_X570_Creator_mit_Thunderbolt_3\" >ASRock X570 Creator mit Thunderbolt 3<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards\/#ASUS_Pro_WS_X570-ACE_mit_Enterprise-Featuers\" >ASUS Pro WS X570-ACE mit Enterprise-Featuers<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards\/#High-End_mit_Hausmitteln\" >High-End mit Hausmitteln?<\/a><\/li><\/ul><\/nav><\/div>\n\n<p class=\"wp-block-paragraph\">Die <strong>Ryzen-Prozessoren<\/strong> von AMD bieten sehr viel Rechenleistung. Das macht sie nicht nur f\u00fcr Gamer interessant. Auch f\u00fcr <strong>Content Creators<\/strong> sind diese CPUs eine gute Wahl. Denn sie eignen sich hervorragend f\u00fcr leistungsstarke, aber preisg\u00fcnstige Workstations. Die Wahl des richtigen Mainboards spielt jedoch eine wichtige Rolle.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/content-creator-workstation-mit-amd-ryzen-und-x570-titelbild-1024x682.jpg\" alt=\"\" class=\"wp-image-5263\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/content-creator-workstation-mit-amd-ryzen-und-x570-titelbild-1024x682.jpg 1024w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/content-creator-workstation-mit-amd-ryzen-und-x570-titelbild-300x200.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/content-creator-workstation-mit-amd-ryzen-und-x570-titelbild-768x512.jpg 768w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/content-creator-workstation-mit-amd-ryzen-und-x570-titelbild-462x308.jpg 462w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/content-creator-workstation-mit-amd-ryzen-und-x570-titelbild.jpg 1040w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>AMD X570 Mainboards f\u00fcr Workstation PCs<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Mit den Matisse-Prozessoren (Ryzen 3000) sind auch neue Hauptplatinen erschienen. Sie setzen auf den <strong>AMD X570-Chipsatz<\/strong>. Mainboards mit diesem AMD-Chip sind mit dem Mainstream-Sockel AM4 ausgestattet. Neben den klassischen Varianten f\u00fcr Heimanwender und Gamer gibt es aber auch Modelle mit dem Namenszusatz &#8222;Creator&#8220; oder &#8222;Creation.&#8220;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Art von Mainboards war bis zum Erscheinen von Ryzen 3000 nur f\u00fcr  HEDT-CPUs&nbsp; wie <strong>Ryzen Threadripper<\/strong> oder <strong>Intel Xeon<\/strong> erh\u00e4ltlich. Was unterscheidet diese Boards vom Rest des Portfolios und was macht sie f\u00fcr Content-Creators interessant?<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\"><span class=\"ez-toc-section\" id=\"Was_ist_ein_Content_Creator\"><\/span>Was ist ein Content Creator?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um das herauszufinden, lohnt sich ein Blick auf die T\u00e4tigkeiten und Arbeitswerkzeuge dieser Personengruppe: <strong>Content-Creation<\/strong> (engl. Inhalte erstellen), h\u00e4ufig auch als DCC (Digital Content Creation) bezeichnet, ist die Erstellung multimedialer Inhalte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dazu geh\u00f6ren Aufgabenbereiche wie 2D- und 3D-Grafikdesign sowie das Erstellen und Bearbeiten von Videos. Auch Webdesign und das Erstellen textbasierter Inhalte mithilfe eines Rechners z\u00e4hlen zur Erstellung von Inhalten.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\"><span class=\"ez-toc-section\" id=\"Leistungsbedarf_von_Programmen\"><\/span>Leistungsbedarf von Programmen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Schreibprogramme stellen heute keine Herausforderung mehr dar. Andere Anwendungen sind deutlich anspruchsvoller. 3D-Applikationen wie <strong>Cinema 4D<\/strong>, Videoschnitt-Programme wie Adobe Premiere Pro und die Compositing- und Animationssoftware <strong>Adobe After Effects<\/strong> ben\u00f6tigen viel Rechenleistung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein leistungsstarker Rechner verk\u00fcrzt die f\u00fcr Berechnungen ben\u00f6tigte Zeit. Projekte werden schneller gerendert. Im Profi-Bereich ist Zeit Geld. Einen solchen Rechner bezeichnet man allgemein als Workstation.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"319\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/workstation-pc-caseking.jpg\" alt=\"\" class=\"wp-image-5264\" style=\"width:588px;height:376px\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/workstation-pc-caseking.jpg 499w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/workstation-pc-caseking-300x192.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/workstation-pc-caseking-462x295.jpg 462w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><figcaption class=\"wp-element-caption\"><em>Eine Workstation kann auch gut aussehen \u2013 mit einer leisen und effektiven Wasserk\u00fchlung<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-left\">Workstation-Performance<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Leistung einer Workstation kann im Prinzip nicht hoch genug sein. Systeme auf Basis von High-End-CPUs wie <strong>Intel Core X<\/strong> oder <strong>AMD Threadripper<\/strong> haben f\u00fcr lange Zeit dieses Maximum an Leistung repr\u00e4sentiert. Viele Prozessorkerne, hohe Taktraten und viel Arbeitsspeicher waren der Spitzenklasse vorbehalten. Der Preis war entsprechend hoch.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr etablierte Firmen stellt der Anschaffungspreis meist auch keine H\u00fcrde dar. Ein <strong>Workstation-Computer <\/strong>holt seine hohen Anschaffungskosten durch die Auftr\u00e4ge wieder rein, die mit seiner Hilfe realisiert werden.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Private und semiprofessionelle Anwender hatten jedoch das Nachsehen. Die Konfiguration eines leistungsstarken PCs mit <strong>Workstation-Performance<\/strong> ist inzwischen g\u00fcnstiger geworden. AMD bietet mit <strong>Ryzen 3000<\/strong> \u201cMatisse\u201d und <strong>Ryzen 5000<\/strong> &#8222;Vermeer&#8220; sehr leistungsf\u00e4hige Prozessoren an.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-left\">Die Kernfrage<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>AMD Ryzen 9 3900X, 3900XT<\/em> und der neuere 5900X verf\u00fcgen \u00fcber <strong>zw\u00f6lf Prozessorkerne. <\/strong>Beide Prozessoren k\u00f6nnen dank <strong>SMT 24 Threads<\/strong> gleichzeitig ausf\u00fchren. Mit dem <em>Ryzen 9 3950X und dem neueren 5950X<\/em> bietet AMD zwei <strong>CPU-Modelle mit 16 Kernen und 32 Threads<\/strong> an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese hohe Anzahl an Threads erm\u00f6glicht dem Prozessor das gleichzeitige Ausf\u00fchren mehrerer Aufgaben. Dadurch k\u00f6nnen verschiedene Programme zur selben Zeit aktiv sein und mehrere Berechnungen parallel durchgef\u00fchrt werden. Davon profitieren insbesondere Bild-, Ton- und Videobearbeitungsprogramme ebenso wie ein Browser mit sehr vielen offenen Tabs.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-left\">So viel Arbeitsspeicher braucht&#8230;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die AMD-Prozessoren der Serien Zen 2 und Zen 3 k\u00f6nnen bis zu <strong>128 Gigabyte <\/strong>Arbeitsspeicher mit extrem hohen Taktraten nutzen. Standardm\u00e4\u00dfig wird <strong>3.200 MHz<\/strong> RAM-Takt unterst\u00fctzt. Das erm\u00f6glicht sehr hohe Daten\u00fcbertragungsraten von bis zu 25,6 GB\/s. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viele Hersteller bieten Arbeitsspeicher mit deutlich h\u00f6heren Taktfrequenzen an, denn <a href=\"https:\/\/www.computerbase.de\/thema\/ram\/rangliste\/\" target=\"_blank\" rel=\"noreferrer noopener\">AMDs Ryzen-CPUs profitieren von einem hohen RAM-Takt<\/a>. Entsprechende Speichermodule verf\u00fcgen neben dem Standardprofil \u00fcber ein zus\u00e4tzliches XMP-Profil zur automatischen Konfiguration der maximalen Leistung. Durch die extrem hohe Bandbreite gelangen die Daten schneller zum Prozessor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr ein fl\u00fcssiges Arbeiten ben\u00f6tigt man einen gro\u00dfen Zwischenspeicher: Aufwendigere Photoshop-Projekte k\u00f6nnen bereits 16 bis 32 GB Arbeitsspeicher bef\u00fcllen. Beim Umgang mit unkomprimiertem Videomaterial professioneller Kameras in 4K mit 120 Bildern pro Sekunde oder 8K ist ein Arbeitsspeicher von mehr als 64 GB durchaus sinnvoll.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-18bbbfb6 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-vivid-cyan-blue-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.caseking.de\/pc-komponenten\/arbeitsspeicher\/ddr4\">Schneller DDR4-Speicher bei Caseking<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Hoehere_Transferraten_und_mehr_Bandbreite_durch_PCI-Express_40\"><\/span><strong>H\u00f6here Transferraten und mehr Bandbreite durch PCI-Express 4.0<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Auch an anderer Stelle sorgt ein Maximum an Bandbreite f\u00fcr beschleunigte Arbeitsabl\u00e4ufe: AMD f\u00fchrte mit der X570-Plattform und den Ryzen-3000-Prozessoren den schnellen PCI-Express-4.0-Standard ein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die entsprechenden Slots verdoppeln die maximale Bandbreite gegen\u00fcber PCI-Express 3.0 auf ca. <strong>2 GB\/s pro Lane<\/strong> und stellen diese f\u00fcr Grafik- und Erweiterungskarten sowie schnelle NVMe-SSDs im M.2-Formfaktor zur Verf\u00fcgung. Die aktuellen Grafikkarten von AMD und NVIDIA unterst\u00fctzen den neuen Standard bereits.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Schnellere Speicher-Laufwerke<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ob Erweiterungskarten mit zus\u00e4tzlichen M.2-Slots, Capture-Devices f\u00fcr Streaming-Zwecke oder dedizierte Soundkarten, die erh\u00f6hte Bandbreite sorgt daf\u00fcr, dass in die Vollen gegriffen werden kann. <strong>Flash-Speicher mit PCIe 4.0<\/strong> sind inzwischen in gro\u00dfer Vielfalt erh\u00e4ltlich. Diese Laufwerke erreichen sehr hohe \u00dcbertragungsraten im Bereich von 5.000 MB\/s und mehr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Palette von Eigenschaften wird schon von der Kombination aus <strong>Matisse- oder Vermeer-Prozessor<\/strong> und einer Hauptplatine mit <em>X570<\/em>&#8211; oder B550-Chipsatz abgedeckt. Beide Plattformen bilden eine gute Basis f\u00fcr den Bau eines leistungsstarken Rechners. AMD X570 unterst\u00fctzt im Vergleich zum B550-Chipsatz mehrere Laufwerke mit PCI Express 4.0.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n<\/div>\n\n\n\n<h1 class=\"wp-block-heading\">Was bieten Workstation-Mainboards mit AMD X570?<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>Creator-Mainboards<\/strong> gehen aber noch einige Schritte weiter und <strong>bieten spezielle Ausstattungsmerkmale<\/strong>, die zur <strong>Konfiguration der idealen Workstation<\/strong> dienen. Bei den Ausstattungsdetails legen die Hersteller dabei Wert auf unterschiedliche Schwerpunkte.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"319\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/4_MSI_prestige_MBMC-348.jpg\" alt=\"\" class=\"wp-image-5266\" style=\"width:579px;height:369px\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/4_MSI_prestige_MBMC-348.jpg 499w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/4_MSI_prestige_MBMC-348-300x192.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/4_MSI_prestige_MBMC-348-462x295.jpg 462w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><figcaption class=\"wp-element-caption\"><em>MSI Prestige X570 Creation Mainboard mit umfangreichem Zubeh\u00f6r<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"MSI_Prestige_X570_Creation_fuer_besonders_viele_NVMe_SSDs\"><\/span><strong>MSI Prestige X570 Creation<\/strong> f\u00fcr besonders viele NVMe SSDs<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><em>MSI<\/em> setzt beim <a href=\"https:\/\/www.caseking.de\/msi-prestige-x570-creation-amd-x570-mainboard-sockel-am4-mbmc-348.html\"><em>Prestige X570 Creation<\/em><\/a> auf eine besonders solide Spannungsversorgung mit acht echten Phasen und versorgt die CPU \u00fcber <strong>zwei 8-Pin-Anschl\u00fcsse<\/strong> mit reichlich elektrischer Energie. Eine effiziente Heatpipe-K\u00fchlung und ein leiser PCH-K\u00fchler mit Doppelkugellager sorgen f\u00fcr einen stabilen Betrieb unter Dauerlast. Auch f\u00fcr die K\u00fchlung der in den zwei M.2-Slots einbaubaren SSDs ist mittels gro\u00dffl\u00e4chiger Passivk\u00fchler gesorgt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dank einer mitgelieferten PCIe-4.0-Erweiterungskarte k\u00f6nnen ab Werk <strong>insgesamt vier M.2-Laufwerke <\/strong>installiert werden. Auf diese Weise kann der Rechner mit einer gro\u00dfen Menge schnellen Flash-Speichers f\u00fcr die Videobearbeitung best\u00fcckt werden.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"319\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/3_PCI_express_MBMC-348.jpg\" alt=\"\" class=\"wp-image-5267\" style=\"width:579px;height:370px\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/3_PCI_express_MBMC-348.jpg 499w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/3_PCI_express_MBMC-348-300x192.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/3_PCI_express_MBMC-348-462x295.jpg 462w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><figcaption class=\"wp-element-caption\"><em>M.2-Steckpl\u00e4tze mit PCI Express 4.0 f\u00fcr die schnellsten SSDs<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Schnelle Laufwerke sind insbesondere bei der Verarbeitung von 4K- und 8K-Videomaterial sinnvoll. Sie erlauben das Betrachten des Videomaterials bei voller Aufl\u00f6sung in Echtzeit. Insgesamt sind <strong>drei PCIe-4.0-x16-Slots<\/strong> vorhanden. So k\u00f6nnen bis zu drei Grafikkarten im Verbund genutzt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">An der I\/O-Blende der Hauptplatine befinden sich neben zahlreichen USB-3-Anschl\u00fcssen auch Antennenanschl\u00fcsse f\u00fcr schnelles <strong>WLAN 802.11ax<\/strong> und zwei Netzwerkanschl\u00fcsse, von denen einer eine maximale Geschwindigkeit von <strong>10 Gbit\/s<\/strong> unterst\u00fctzt. So wird ein schneller Datenaustausch mit Netzwerkspeichern und Servern gew\u00e4hrleistet.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"319\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/11_MBAR-308.jpg\" alt=\"\" class=\"wp-image-5268\" style=\"width:577px;height:369px\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/11_MBAR-308.jpg 499w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/11_MBAR-308-300x192.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/11_MBAR-308-462x295.jpg 462w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><figcaption class=\"wp-element-caption\"><em>Das ASRock X570 Creator bietet schnelles Thunderbolt 3<\/em><\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"ASRock_X570_Creator_mit_Thunderbolt_3\"><\/span><strong>ASRock X570 Creator<\/strong> mit Thunderbolt 3<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eine dedizierte Erweiterungskarte f\u00fcr M.2-Laufwerke spendiert <em>ASRock<\/em> dem <a href=\"https:\/\/www.caseking.de\/asrock-x570-creator-amd-x570-mainboard-sockel-am4-mbar-308.html\"><em>X570 Creator<\/em><\/a> nicht. Stattdessen setzt der Hersteller auf <strong>Konnektivit\u00e4t<\/strong>: Neben zahlreichen USB-Anschl\u00fcssen, Dual-LAN und den WLAN-Antennenanschl\u00fcssen befinden sich gleich <strong>zwei Thunderbolt-3-Anschl\u00fcsse<\/strong> an der I\/O-Blende der Platine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcber Thunderbolt 3 ist die externe Anbindung von PCI-Express-Ger\u00e4ten m\u00f6glich. So k\u00f6nnen neben der \u00fcblichen Peripherie, Smartphones und Tablets auch externe Grafikkarten und portable NVMe-SSDs mit dem Rechner verbunden werden. Die Schnittstelle erreicht eine maximale \u00dcbertragungsrate von <strong>40 Gigabit pro Sekunde<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"229\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/12_I-O_panel_MBAR-308.jpg\" alt=\"\" class=\"wp-image-5269\" style=\"width:577px;height:265px\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/12_I-O_panel_MBAR-308.jpg 499w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/12_I-O_panel_MBAR-308-300x138.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/12_I-O_panel_MBAR-308-462x212.jpg 462w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><figcaption class=\"wp-element-caption\"><em>Zahlreiche n\u00fctzliche Anschl\u00fcsse f\u00fcr umfangreiches Zubeh\u00f6r wie externe Laufwerke<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Auf dem Mainboard selbst befinden sich zwei M.2- und drei PCIe-4.0-x16-Steckpl\u00e4tze. F\u00fcr eine schnelle Netzwerkanbindung sorgen auch beim <a href=\"https:\/\/www.caseking.de\/asrock-x570-creator-amd-x570-mainboard-sockel-am4-mbar-308.html\">ASRock X570 Creator<\/a> ein 10-Gigabit-Anschluss sowie <strong>WLAN 802.11ax<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Leistungsaufnahme der CPU wird per 8-Pin- und 4-Pin-Stecker gedeckt. Auf den Spannungswandlern ist eine gro\u00dffl\u00e4chige Heatpipe-K\u00fchlung verbaut, sodass diese auch bei intensiver Beanspruchung k\u00fchl bleiben. Der Chipsatz wird aktiv und die in den M.2-Slots platzierten SSDs passiv gek\u00fchlt.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"319\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/7_ASUS_Pro_WS_X570_MBAS-456.jpg\" alt=\"\" class=\"wp-image-5271\" style=\"width:579px;height:370px\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/7_ASUS_Pro_WS_X570_MBAS-456.jpg 499w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/7_ASUS_Pro_WS_X570_MBAS-456-300x192.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/7_ASUS_Pro_WS_X570_MBAS-456-462x295.jpg 462w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><figcaption class=\"wp-element-caption\"><em>Das ASUS Pro WS X570-ACE ist schlicht, aber hochwertig und zuverl\u00e4ssig. <\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"ASUS_Pro_WS_X570-ACE_mit_Enterprise-Featuers\"><\/span><strong>ASUS Pro WS X570-ACE<\/strong> mit Enterprise-Featuers<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das <a href=\"https:\/\/www.caseking.de\/asus-pro-ws-x570-ace-amd-x570-mainboard-sockel-am4-mbas-456.html\"><em>ASUS Pro WS X570-ACE<\/em><\/a> bietet acht reale Phasen. Der Hersteller setzt durchweg auf hochwertige elektrische Bauteile und einen im Vergleich zu den oben genannten Modellen schlichten, sachlichen Look. Die AM4-Hauptplatine <strong>unterst\u00fctzt Arbeitsspeicher mit ECC<\/strong> (Error-Correcting Code). Diese Speichermodule werden \u00fcblicherweise in Servern eingesetzt und sind in der Lage, mittels einer Kodierung Fehler im RAM zu erkennen und zu korrigieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine weitere Besonderheit dieser Hauptplatine sind die <strong>drei PCIe-4.0-x16-Slots, die gleichzeitig mit jeweils acht Lanes<\/strong> (PCIe 4.0 x8) genutzt werden k\u00f6nnen. So wird eine enorme Bandbreite f\u00fcr separate Erweiterungskarten mit M.2-Slots oder mehrere Grafikkarten gleichzeitig bereitgestellt. \u00dcberdies bietet das Board einen <strong>U.2-Anschluss<\/strong> f\u00fcr Enterprise-SSDs und einen <strong>10-Gigabit-LAN<\/strong>-Port f\u00fcr eine schnelle Netzwerkanbindung.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"319\" src=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/9_ASUS_Pro_WS_X570_electrical_parts_MBAS-456.jpg\" alt=\"\" class=\"wp-image-5273\" style=\"width:574px;height:366px\"\/ loading=\"lazy\" srcset=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/9_ASUS_Pro_WS_X570_electrical_parts_MBAS-456.jpg 499w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/9_ASUS_Pro_WS_X570_electrical_parts_MBAS-456-300x192.jpg 300w, https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/9_ASUS_Pro_WS_X570_electrical_parts_MBAS-456-462x295.jpg 462w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><figcaption class=\"wp-element-caption\"><em>Drei PCI-Express 4.0 x16 Steckpl\u00e4tze mit achtfacher Geschwindigkeit.<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Eine zus\u00e4tzliche Grafikkarten-Halterung liegt dem Mainboard bei. Diese sorgt f\u00fcr mehr Stabilit\u00e4t und durch die M\u00f6glichkeit zur Montage eines 120-Millimeter-L\u00fcfters auch f\u00fcr eine bessere K\u00fchlung von bis zu zwei Grafikkarten. Jedes <strong>ASUS Pro WS X570-ACE<\/strong> wird in einem 24-Stunden-Stresstest bei 45 \u00b0C Raumtemperatur und 80 Prozent Luftfeuchtigkeit auf seine Verl\u00e4sslichkeit gepr\u00fcft.<\/p>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"High-End_mit_Hausmitteln\"><\/span><strong>High-End mit Hausmitteln?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Herangehensweisen der Hesteller an das Thema Workstation sind unterschiedlich. Trotzdem basieren sie auf dem gleichen Gedanken: Den <strong>Bau einer echten Workstation mit herk\u00f6mmlichen Desktop-Prozessoren<\/strong> wie den <em>Ryzen<\/em>-CPUs der dritten Generation zu erm\u00f6glichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Den Grundstein setzt AMD mit der Erh\u00f6hung der CPU-Kerne, der <strong>Unterst\u00fctzung von 128 GB Arbeitsspeicher<\/strong> <strong>und PCI-Express 4.0.<\/strong> Erg\u00e4nzend setzen die Mainboard-Hersteller auf hochwertige Bauteile, intensive K\u00fchlung und die aktuellsten Schnittstellen, um ein solides Fundament f\u00fcr den professionellen Einsatz zu erschaffen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit den neuen Ryzen-5000-CPUs erweitert AMD au\u00dferdem den Horizont der AM4-Plattform und bietet Kreativen ein attraktives Portfolio leistungsstarker Prozessoren. Mit Zen 3 geh\u00f6rt langes Warten der Vergangenheit an. Die Technik setzt deiner Fantasie keine Grenzen mehr.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-18bbbfb6 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-vivid-cyan-blue-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.caseking.de\/pc-komponenten\/cpus-prozessoren\/amd?stockids=hpam-202%2Chpam-203%2Chpam-204%2Chpam-205\">Die AMD Ryzen 5000 CPUs bei Caseking<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Content Creator? AMD bietet mit Ryzen und X570 die richtige Plattform f\u00fcr deine Workstation.<\/p>\n","protected":false},"author":22,"featured_media":5262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2233,2231],"tags":[220,631,739,280,2309,2296,1381],"class_list":["post-5045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-content-creation","category-tech","tag-amd-ryzen","tag-amd-x570","tag-pc","tag-ryzen-3000","tag-ryzen-5000","tag-vermeer","tag-workstation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AMD Ryzen Workstation Mainboads mit AMD X570<\/title>\n<meta name=\"description\" content=\"Du willst eine Workstation mit AMD Ryzen bauen? Das sind die besten Workstation-Mainboards mit AMD X570 Chipsatz f\u00fcr deine Ryzen 3000 oder Ryzen 5000 CPU.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AMD Ryzen Workstation Mainboads mit AMD X570\" \/>\n<meta property=\"og:description\" content=\"Du willst eine Workstation mit AMD Ryzen bauen? Das sind die besten Workstation-Mainboards mit AMD X570 Chipsatz f\u00fcr deine Ryzen 3000 oder Ryzen 5000 CPU.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards\" \/>\n<meta property=\"og:site_name\" content=\"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/caseking\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-06T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T08:34:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/title_image_DE_255x255.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"255\" \/>\n\t<meta property=\"og:image:height\" content=\"255\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marcel Fleischer\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marcel Fleischer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AMD Ryzen Workstation Mainboads mit AMD X570","description":"Du willst eine Workstation mit AMD Ryzen bauen? Das sind die besten Workstation-Mainboards mit AMD X570 Chipsatz f\u00fcr deine Ryzen 3000 oder Ryzen 5000 CPU.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards","og_locale":"de_DE","og_type":"article","og_title":"AMD Ryzen Workstation Mainboads mit AMD X570","og_description":"Du willst eine Workstation mit AMD Ryzen bauen? Das sind die besten Workstation-Mainboards mit AMD X570 Chipsatz f\u00fcr deine Ryzen 3000 oder Ryzen 5000 CPU.","og_url":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards","og_site_name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","article_publisher":"https:\/\/www.facebook.com\/caseking\/","article_published_time":"2020-11-06T06:00:00+00:00","article_modified_time":"2025-04-01T08:34:18+00:00","og_image":[{"width":255,"height":255,"url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/title_image_DE_255x255.jpg","type":"image\/jpeg"}],"author":"Marcel Fleischer","twitter_misc":{"Verfasst von":"Marcel Fleischer","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards#article","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards"},"author":{"name":"Marcel Fleischer","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/9e94f778157d45a98ed685f597b32da0"},"headline":"Content Creator Workstation mit AMD Ryzen und X570","datePublished":"2020-11-06T06:00:00+00:00","dateModified":"2025-04-01T08:34:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards"},"wordCount":1612,"commentCount":0,"publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/title_image_DE_255x255.jpg","keywords":["AMD Ryzen","AMD X570","PC","Ryzen 3000","Ryzen 5000","Vermeer","Workstation"],"articleSection":["Content Creation","Tech"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards","url":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards","name":"AMD Ryzen Workstation Mainboads mit AMD X570","isPartOf":{"@id":"https:\/\/www.caseking.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards#primaryimage"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards#primaryimage"},"thumbnailUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/title_image_DE_255x255.jpg","datePublished":"2020-11-06T06:00:00+00:00","dateModified":"2025-04-01T08:34:18+00:00","description":"Du willst eine Workstation mit AMD Ryzen bauen? Das sind die besten Workstation-Mainboards mit AMD X570 Chipsatz f\u00fcr deine Ryzen 3000 oder Ryzen 5000 CPU.","breadcrumb":{"@id":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards#primaryimage","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/title_image_DE_255x255.jpg","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2020\/11\/title_image_DE_255x255.jpg","width":255,"height":255,"caption":"Die Wahl des richtigen Mainboards ist ein elementarer Baustein f\u00fcr deine Workstation."},{"@type":"BreadcrumbList","@id":"https:\/\/www.caseking.de\/blog\/amd-ryzen-workstation-mainboards#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.caseking.de\/blog"},{"@type":"ListItem","position":2,"name":"Tech","item":"https:\/\/www.caseking.de\/blog\/category\/tech"},{"@type":"ListItem","position":3,"name":"Content Creation","item":"https:\/\/www.caseking.de\/blog\/category\/tech\/content-creation"},{"@type":"ListItem","position":4,"name":"Content Creator Workstation mit AMD Ryzen und X570"}]},{"@type":"WebSite","@id":"https:\/\/www.caseking.de\/blog\/#website","url":"https:\/\/www.caseking.de\/blog\/","name":"Caseking Blog | Gaming-PCs, Hardware-News &amp; Modding-Guides","description":"Die neuesten Hardware und Games News, Ger\u00fcchte, Trends und vieles mehr","publisher":{"@id":"https:\/\/www.caseking.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.caseking.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.caseking.de\/blog\/#organization","name":"Caseking GmbH","url":"https:\/\/www.caseking.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","contentUrl":"https:\/\/www.caseking.de\/blog\/wp-content\/uploads\/2021\/09\/logo.png","width":367,"height":200,"caption":"Caseking GmbH"},"image":{"@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/caseking\/","https:\/\/x.com\/caseking","https:\/\/www.instagram.com\/caseking.de","https:\/\/www.linkedin.com\/company\/caseking-gmbh\/","https:\/\/www.youtube.com\/channel\/UC8qA3SSeY04t_lWumt_SgEg"]},{"@type":"Person","@id":"https:\/\/www.caseking.de\/blog\/#\/schema\/person\/9e94f778157d45a98ed685f597b32da0","name":"Marcel Fleischer","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f4de02015770980dd8dad6afa7e03668e2762d9d35982d9e5381871de6427ba5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4de02015770980dd8dad6afa7e03668e2762d9d35982d9e5381871de6427ba5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4de02015770980dd8dad6afa7e03668e2762d9d35982d9e5381871de6427ba5?s=96&d=mm&r=g","caption":"Marcel Fleischer"},"description":"Marcel stammt aus Dresden und hat sich schon sehr fr\u00fch f\u00fcr Hardware und Technologie begeistert. Seine berufliche Erfahrung im Bereich IT und PC-Hardware sowie seine Leidenschaft f\u00fcr Custom-Wasserk\u00fchlungen und Overclocking pr\u00e4gen seine Beitr\u00e4ge im Caseking Blog. Hier schreibt Marcel \u00fcber Hardware-Innovationen, Technologie und spannende Trends rund um PC-Builds und Gaming. In seiner Freizeit verfolgt er die neuesten Techniktrends unter anderem von 'den Steves' - Gamers Nexus und Hardware Unboxed - und entspannt sich bei Spielen wie Path of Exile 2, Call of Duty oder spannenden Singleplayer-Abenteuern.","url":"https:\/\/www.caseking.de\/blog\/author\/mfleischer"}]}},"_links":{"self":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/5045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/comments?post=5045"}],"version-history":[{"count":51,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/5045\/revisions"}],"predecessor-version":[{"id":22318,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/posts\/5045\/revisions\/22318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media\/5262"}],"wp:attachment":[{"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/media?parent=5045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/categories?post=5045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caseking.de\/blog\/wp-json\/wp\/v2\/tags?post=5045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}